{"id":123,"count":0,"description":"","link":"http:\/\/www.universalsteelbd.com\/blog\/tag\/emergency-light-49da-83fb00\/","name":"Emergency Light","slug":"emergency-light-49da-83fb00","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/tags\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/posts?tags=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}