{"id":489,"count":0,"description":"","link":"http:\/\/www.universalsteelbd.com\/blog\/tag\/motor-generator-magnets-432e-10cb12\/","name":"Motor \/ Generator Magnets","slug":"motor-generator-magnets-432e-10cb12","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/tags\/489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/posts?tags=489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}