{"id":60,"count":0,"description":"","link":"http:\/\/www.universalsteelbd.com\/blog\/tag\/military-wheels-4a5d-ae1485\/","name":"Military Wheels","slug":"military-wheels-4a5d-ae1485","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/tags\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/posts?tags=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}