{"id":145,"name":"philip","url":"http:\/\/www.hungso.com","description":"","link":"http:\/\/www.universalsteelbd.com\/blog\/author\/philip\/","slug":"philip","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c59b859d2eaede4f09a6a1c2765c970b70d3e000f30d892933b637164e0446e6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c59b859d2eaede4f09a6a1c2765c970b70d3e000f30d892933b637164e0446e6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c59b859d2eaede4f09a6a1c2765c970b70d3e000f30d892933b637164e0446e6?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/users\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/users"}]}}