{"id":164,"name":"elyse","url":"http:\/\/www.jinhehardware.com","description":"","link":"http:\/\/www.universalsteelbd.com\/blog\/author\/elyse\/","slug":"elyse","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c34fe4633e6bd3264527760c7c9a8b2a3cdeb7e9d501b42f97ee8d12a906157c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c34fe4633e6bd3264527760c7c9a8b2a3cdeb7e9d501b42f97ee8d12a906157c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c34fe4633e6bd3264527760c7c9a8b2a3cdeb7e9d501b42f97ee8d12a906157c?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/users\/164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/users"}]}}