{"id":230,"name":"donna","url":"http:\/\/www.sanying-valve.com","description":"","link":"http:\/\/www.universalsteelbd.com\/blog\/author\/donna\/","slug":"donna","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/df25080c0e4868d397e92706435d0fffc6848f471f0e9befcf15533a0f543007?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/df25080c0e4868d397e92706435d0fffc6848f471f0e9befcf15533a0f543007?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/df25080c0e4868d397e92706435d0fffc6848f471f0e9befcf15533a0f543007?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/users\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.universalsteelbd.com\/blog\/wp-json\/wp\/v2\/users"}]}}